{"id":3361,"date":"2020-05-28T20:00:22","date_gmt":"2020-05-28T20:00:22","guid":{"rendered":"https:\/\/dorantesadvisors.com\/?p=3361"},"modified":"2024-10-23T22:48:04","modified_gmt":"2024-10-23T22:48:04","slug":"comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad","status":"publish","type":"post","link":"https:\/\/dorantesadvisors.com\/en\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/","title":{"rendered":"Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad"},"content":{"rendered":"<div\n    class='wp-block-pdfp-pdf-poster  alignnone'\n    id='block-2'\n    data-attributes='{&quot;uniqueId&quot;:&quot;pdfp1&quot;,&quot;file&quot;:&quot;https:\\\/\\\/dorantesadvisors.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/2020-05-15-Comentarios-sobre-LIC-FINAL.pdf&quot;,&quot;title&quot;:&quot;Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad&quot;,&quot;height&quot;:&quot;842px&quot;,&quot;width&quot;:&quot;100%&quot;,&quot;print&quot;:false,&quot;fullscreenButton&quot;:true,&quot;fullscreenButtonText&quot;:&quot;Fullscreen&quot;,&quot;newWindow&quot;:false,&quot;showName&quot;:false,&quot;downloadButton&quot;:true,&quot;downloadButtonText&quot;:&quot;Download File&quot;,&quot;protect&quot;:false,&quot;onlyPDF&quot;:false,&quot;defaultBrowser&quot;:false,&quot;thumbMenu&quot;:false,&quot;initialPage&quot;:&quot;1&quot;,&quot;sidebarOpen&quot;:false,&quot;lastVersion&quot;:false,&quot;hrScroll&quot;:false,&quot;alert&quot;:false,&quot;btnStyles&quot;:{&quot;background&quot;:&quot;#1e73be&quot;,&quot;color&quot;:&quot;#fff&quot;,&quot;fontSize&quot;:&quot;rem&quot;,&quot;padding&quot;:{&quot;top&quot;:10,&quot;right&quot;:20,&quot;bottom&quot;:10,&quot;left&quot;:10}},&quot;popupOptions&quot;:{&quot;enabled&quot;:false,&quot;text&quot;:&quot;Open PDF&quot;,&quot;btnStyle&quot;:{&quot;background&quot;:&quot;#1e73be&quot;,&quot;color&quot;:&quot;#fff&quot;,&quot;fontSize&quot;:&quot;rem&quot;,&quot;padding&quot;:{&quot;top&quot;:10,&quot;right&quot;:20,&quot;bottom&quot;:10,&quot;left&quot;:10}}},&quot;align&quot;:&quot;none&quot;,&quot;alignment&quot;:&quot;left&quot;,&quot;titleFontSize&quot;:&quot;16px&quot;,&quot;isHideRightToolbar&quot;:false,&quot;additional&quot;:{&quot;ID&quot;:&quot;&quot;,&quot;Class&quot;:&quot;&quot;,&quot;CSS&quot;:&quot;&quot;},&quot;adobeEmbedder&quot;:false,&quot;adobeOptions&quot;:{&quot;showDownloadPDF&quot;:true,&quot;showPrintPDF&quot;:true,&quot;showAnnotationTools&quot;:true,&quot;showFullScreen&quot;:false,&quot;embedMode&quot;:&quot;SIZED_CONTAINER&quot;},&quot;popupBtnStyle&quot;:{&quot;background&quot;:&quot;#2271b1&quot;,&quot;color&quot;:&quot;#fff&quot;,&quot;padding&quot;:{&quot;top&quot;:10,&quot;right&quot;:20,&quot;bottom&quot;:10,&quot;left&quot;:10}},&quot;popupBtnText&quot;:&quot;Open Document&quot;,&quot;CSS&quot;:&quot;&quot;,&quot;TrpContentRestriction&quot;:{&quot;restriction_type&quot;:&quot;exclude&quot;,&quot;selected_languages&quot;:[],&quot;panel_open&quot;:true}}'\n    style=\"text-align: left\">\n    \n        <iframe title=\"Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad\" style=\"border:0;\" width=\"100%\" height=\"800px\" class=\"pdfp_unsupported_frame\" src=\"\/\/docs.google.com\/gview?embedded=true&url=https:\/\/dorantesadvisors.com\/wp-content\/uploads\/2024\/10\/2020-05-15-Comentarios-sobre-LIC-FINAL.pdf\"><\/iframe>\n\n    <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3241,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-3361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad - Dorantes Advisors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorantesadvisors.com\/en\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad - Dorantes Advisors\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorantesadvisors.com\/en\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Dorantes Advisors\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-28T20:00:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-23T22:48:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dorantesadvisors.com\/wp-content\/uploads\/2022\/10\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Dorantes Advisors\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dorantes Advisors\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/\",\"url\":\"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/\",\"name\":\"Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad - Dorantes Advisors\",\"isPartOf\":{\"@id\":\"https:\/\/dorantesadvisors.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dorantesadvisors.com\/wp-content\/uploads\/2022\/10\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad.webp\",\"datePublished\":\"2020-05-28T20:00:22+00:00\",\"dateModified\":\"2024-10-23T22:48:04+00:00\",\"author\":{\"@id\":\"https:\/\/dorantesadvisors.com\/#\/schema\/person\/2d5fe34e6f8006b7d5d83afc214b394d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/#primaryimage\",\"url\":\"https:\/\/dorantesadvisors.com\/wp-content\/uploads\/2022\/10\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad.webp\",\"contentUrl\":\"https:\/\/dorantesadvisors.com\/wp-content\/uploads\/2022\/10\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad.webp\",\"width\":770,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/dorantesadvisors.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dorantesadvisors.com\/#website\",\"url\":\"https:\/\/dorantesadvisors.com\/\",\"name\":\"Dorantes Advisors\",\"description\":\"Derecho y Asuntos Internacionales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dorantesadvisors.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dorantesadvisors.com\/#\/schema\/person\/2d5fe34e6f8006b7d5d83afc214b394d\",\"name\":\"Dorantes Advisors\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dorantesadvisors.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a337263c3eec976df254daa62980f1b6b834802722cfd212c0b5c713ea16081b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a337263c3eec976df254daa62980f1b6b834802722cfd212c0b5c713ea16081b?s=96&d=mm&r=g\",\"caption\":\"Dorantes Advisors\"},\"sameAs\":[\"https:\/\/dorantesadvisors.com\"],\"url\":\"https:\/\/dorantesadvisors.com\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad - Dorantes Advisors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorantesadvisors.com\/en\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/","og_locale":"en_US","og_type":"article","og_title":"Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad - Dorantes Advisors","og_url":"https:\/\/dorantesadvisors.com\/en\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/","og_site_name":"Dorantes Advisors","article_published_time":"2020-05-28T20:00:22+00:00","article_modified_time":"2024-10-23T22:48:04+00:00","og_image":[{"width":770,"height":460,"url":"https:\/\/dorantesadvisors.com\/wp-content\/uploads\/2022\/10\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad.webp","type":"image\/webp"}],"author":"Dorantes Advisors","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dorantes Advisors"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/","url":"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/","name":"Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad - Dorantes Advisors","isPartOf":{"@id":"https:\/\/dorantesadvisors.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/#primaryimage"},"image":{"@id":"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/#primaryimage"},"thumbnailUrl":"https:\/\/dorantesadvisors.com\/wp-content\/uploads\/2022\/10\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad.webp","datePublished":"2020-05-28T20:00:22+00:00","dateModified":"2024-10-23T22:48:04+00:00","author":{"@id":"https:\/\/dorantesadvisors.com\/#\/schema\/person\/2d5fe34e6f8006b7d5d83afc214b394d"},"breadcrumb":{"@id":"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/#primaryimage","url":"https:\/\/dorantesadvisors.com\/wp-content\/uploads\/2022\/10\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad.webp","contentUrl":"https:\/\/dorantesadvisors.com\/wp-content\/uploads\/2022\/10\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad.webp","width":770,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/dorantesadvisors.com\/2020\/05\/28\/comentarios-al-proyecto-de-decreto-por-el-que-se-expide-la-ley-de-infraestructura-de-la-calidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dorantesadvisors.com\/"},{"@type":"ListItem","position":2,"name":"Comentarios al proyecto de decreto por el que se expide la Ley de Infraestructura de la Calidad"}]},{"@type":"WebSite","@id":"https:\/\/dorantesadvisors.com\/#website","url":"https:\/\/dorantesadvisors.com\/","name":"Dorantes Advisors","description":"Derecho y Asuntos Internacionales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorantesadvisors.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/dorantesadvisors.com\/#\/schema\/person\/2d5fe34e6f8006b7d5d83afc214b394d","name":"Dorantes Advisors","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dorantesadvisors.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a337263c3eec976df254daa62980f1b6b834802722cfd212c0b5c713ea16081b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a337263c3eec976df254daa62980f1b6b834802722cfd212c0b5c713ea16081b?s=96&d=mm&r=g","caption":"Dorantes Advisors"},"sameAs":["https:\/\/dorantesadvisors.com"],"url":"https:\/\/dorantesadvisors.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/posts\/3361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/comments?post=3361"}],"version-history":[{"count":3,"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/posts\/3361\/revisions"}],"predecessor-version":[{"id":3432,"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/posts\/3361\/revisions\/3432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/media\/3241"}],"wp:attachment":[{"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/media?parent=3361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/categories?post=3361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorantesadvisors.com\/en\/wp-json\/wp\/v2\/tags?post=3361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}